{"id":193,"date":"2023-06-29T04:41:11","date_gmt":"2023-06-29T04:41:11","guid":{"rendered":"https:\/\/www.haustrocknung.ch\/?page_id=193"},"modified":"2026-06-20T23:28:03","modified_gmt":"2026-06-20T22:28:03","slug":"sockelheizung","status":"publish","type":"page","link":"https:\/\/www.haustrocknung.ch\/de\/sockelheizung\/","title":{"rendered":"CH \/ Heizung \/ Sockelheizung"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"193\" class=\"elementor elementor-193\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb394b4 elementor-section-full_width elementor-section-height-min-height elementor-section-items-stretch elementor-section-height-default\" data-id=\"bb394b4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-294652c\" data-id=\"294652c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10cb98e7 elementor-widget elementor-widget-heading\" data-id=\"10cb98e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Kosten sparen mit einer<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f413cf4 elementor-widget elementor-widget-heading\" data-id=\"7f413cf4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Sockelheizung<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ff04e6b elementor-widget elementor-widget-text-editor\" data-id=\"2ff04e6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bei den \u00fcblichen Radiatoren bezahlen Sie mind. 20\u00a0% zu viel f\u00fcrs Heizen, weil sich ein Gross\u00adteil der W\u00e4rme ungenutzt unter der Decke ansammelt. Heizen Sie Ihre R\u00e4ume gleich\u00adm\u00e4ssig mit einer Sockel\u00adheizung und bezahlen Sie nicht mehr zu viel.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-679837a elementor-widget elementor-widget-button\" data-id=\"679837a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"#offerte\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt Offerte anfragen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8cc6441\" data-id=\"8cc6441\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd4d804 elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-image\" data-id=\"cd4d804\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"248\" height=\"620\" src=\"https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/07\/drop-mood-blue.svg\" class=\"attachment-large size-large wp-image-439\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-66b5be4\" data-id=\"66b5be4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fbab94 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"0fbab94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/07\/sockelheizung-header-1024x682.jpg\" class=\"attachment-large size-large wp-image-4057\" alt=\"Sockelheizung\" srcset=\"https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/07\/sockelheizung-header-1024x682.jpg 1024w, https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/07\/sockelheizung-header-300x200.jpg 300w, https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/07\/sockelheizung-header-768x512.jpg 768w, https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/07\/sockelheizung-header-18x12.jpg 18w, https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/07\/sockelheizung-header.jpg 1168w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2445657c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2445657c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c36d305\" data-id=\"2c36d305\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5755b348 elementor-align-left elementor-widget elementor-widget-breadcrumbs\" data-id=\"5755b348\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.haustrocknung.ch\/\">Startseite<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0674812 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0674812\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-471b106\" data-id=\"471b106\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17ac0ca elementor-widget elementor-widget-heading\" data-id=\"17ac0ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">So funktioniert's<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a33145e elementor-widget elementor-widget-heading\" data-id=\"a33145e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sockelleistenheizung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fac0fc9 elementor-widget elementor-widget-text-editor\" data-id=\"fac0fc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Sockelleistenhei\u00adzung ist ein lang\u00adge\u00adzogener Heiz\u00adk\u00f6rper in der Form einer Sockel\u00adleiste, der entlang der gesamten Wand\u00adl\u00e4nge verl\u00e4uft. \u00c4hnlich wie bei herk\u00f6mm\u00adli\u00adchen Heiz\u00adradia\u00adtoren steigt aus der Fuss\u00adleisten\u00adheizung warme Luft auf. Damit wird jedoch nicht die Raumluft aufgeheizt, sondern lediglich die Ober\u00adfl\u00e4chen der W\u00e4nde.<\/p><p>Die erw\u00e4rmten Wandober\u00adfl\u00e4chen strahlen anschlies\u00adsend, wie ein Kachel\u00adofen, W\u00e4rme\u00adstrah\u00adlung in den Raum ab und heizen so den Raum gleich\u00adm\u00e4ssig auf. Damit spart man bis zu 30\u00a0% Heiz\u00adkosten, weil sich nicht ein Gross\u00adteil der W\u00e4rme ungenutzt unter der Decke ansammelt. Die aufgewendete Energie muss lediglich die Wand\u00adober\u00adfl\u00e4che aufheizen &#8211; nicht das ganze Raumluftvolumen.<\/p><p>Abgesehen von tieferen Heiz\u00adkosten sorgt die Sockel\u00adheizung, als energie\u00adeffi\u00adzientes, umwelt\u00adfreund\u00adli\u00adches Heiz\u00adsystem, f\u00fcr ein gesundes Raumklima. Sie sorgt auch an kritischen Stellen wie dem Boden-Wand-Anschluss f\u00fcr angenehme, gleich\u00adm\u00e4ssige W\u00e4rme. Dadurch reduziert sich die Gefahr von Konden\u00adsa\u00adtion und Schimmelbildung.<\/p><p>Egal, wie die Immobilie genutzt wird, ob als Wohnhaus, Gewerbe oder \u00f6ffentliches Geb\u00e4ude \u2013 die Sockel\u00adheiz\u00adleisten sind optisch ansprechend und flexibel einsetzbar. Sockel\u00adheizungen k\u00f6nnen mit Strom oder Wasser betrieben werden. Eine Installation der Sockel\u00adheiz\u00adleiste ist schnell und einfach sowie auch nach\u00adtr\u00e4g\u00adlich m\u00f6glich. Auch Sie k\u00f6nnen von unseren Sockel\u00adheiz\u00adleisten profitieren. <a title=\"Jetzt anfragen\" href=\"#offerte\">Fragen Sie uns unverbindlich an.<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-91357b9 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"91357b9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-01e068d\" data-id=\"01e068d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-713469c elementor-widget elementor-widget-heading\" data-id=\"713469c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Unsere Leistungen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ea744d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1ea744d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sorgf\u00e4ltige Identifikation der Heizsituation<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Erstellung eines Konzepts ausgerichtet auf die Ursachen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Grundlegende L\u00f6sung des K\u00e4lteproblems<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c22c095\" data-id=\"c22c095\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fba9704 elementor-widget elementor-widget-heading\" data-id=\"fba9704\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ihre Vorteile<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fec9718 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"fec9718\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Beratung von erfahrenen Bau&shy;ingenieuren oder Baubiologen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Untersuchung und -sanierung aus einer Hand<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Angebot weiterer kosteng\u00fcnstiger Alternativl\u00f6sungen m\u00f6glich<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Kostentransparenz als Selbstverst\u00e4ndlichkeit<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f6aaeb6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f6aaeb6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f33befd\" data-id=\"f33befd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1293ca elementor-widget elementor-widget-menu-anchor\" data-id=\"a1293ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"offerte\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbf029d elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-widescreen elementor-widget elementor-widget-image\" data-id=\"bbf029d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"1013\" src=\"https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/07\/tobias-bayer-809x1024.png\" class=\"attachment-large size-large wp-image-2522\" alt=\"Tobias Bayer Profilbild\" srcset=\"https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/07\/tobias-bayer-809x1024.png 809w, https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/07\/tobias-bayer-237x300.png 237w, https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/07\/tobias-bayer-768x972.png 768w, https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/07\/tobias-bayer-9x12.png 9w, https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/07\/tobias-bayer.png 904w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a0025d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a0025d0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3e94b40\" data-id=\"3e94b40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e63050 elementor-widget elementor-widget-heading\" data-id=\"9e63050\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kontaktieren Sie uns&nbsp;unverbindlich<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c37b36 elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"2c37b36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Haben Sie weitere Fragen oder d\u00fcrfen wir f\u00fcr Sie eine Offerte erstellen?<\/p><p>Nehmen Sie unverbindlich Kontakt mit uns auf. Wir freuen uns auf Ihre Anfrage!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7b0d1e elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-widescreen elementor-widget elementor-widget-text-editor\" data-id=\"e7b0d1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nehmen Sie unverbindlich Kontakt mit uns auf. Wir freuen uns auf Ihre Anfrage!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b15fcaf elementor-widget elementor-widget-text-editor\" data-id=\"b15fcaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><strong>Tobias Bayer<\/strong><br \/>Gesch\u00e4ftsf\u00fchrer<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7af9ca5 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"7af9ca5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"972\" src=\"https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/07\/tobias-bayer-left-768x972.png\" class=\"attachment-medium_large size-medium_large wp-image-2524\" alt=\"Tobias Bayer Profilbild\" srcset=\"https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/07\/tobias-bayer-left-768x972.png 768w, https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/07\/tobias-bayer-left-237x300.png 237w, https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/07\/tobias-bayer-left-809x1024.png 809w, https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/07\/tobias-bayer-left-9x12.png 9w, https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/07\/tobias-bayer-left.png 904w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-125eb3b\" data-id=\"125eb3b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c6822e6 elementor-button-align-stretch elementor-widget elementor-widget-global elementor-global-11621 elementor-widget-form\" data-id=\"c6822e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"193\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"c6822e6\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Haustrocknung.ch\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tFirma \/ Organisation\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Firma \/ Organisation\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_5946aef elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_5946aef\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tVorname\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_5946aef]\" id=\"form-field-field_5946aef\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Vorname*\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_d2f6ce7 elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_d2f6ce7\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNachname\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_d2f6ce7]\" id=\"form-field-field_d2f6ce7\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nachname*\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_806277a elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_806277a\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tAdresse\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_806277a]\" id=\"form-field-field_806277a\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Adresse*\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_16182cc elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_16182cc\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tPLZ \/ Ort\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_16182cc]\" id=\"form-field-field_16182cc\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"PLZ und Ort*\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tE-Mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"E-Mail*\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_2eb330f elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_2eb330f\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tTelefon\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_2eb330f]\" id=\"form-field-field_2eb330f\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Telefon*\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNachricht\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Nachricht*\" required=\"required\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_af7d92b elementor-col-100 recaptcha_v3-inline\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_af7d92b\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LcsTWcoAAAAAG4NvVcLzAAIx0ejeIuaLguvNQdM\" data-type=\"v3\" data-action=\"Form\" data-badge=\"inline\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Senden<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-73a3979 e-flex e-con-boxed e-con e-parent\" data-id=\"73a3979\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-813c8a2 e-flex e-con-boxed e-con e-child\" data-id=\"813c8a2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a4214ad e-n-tabs-none elementor-widget elementor-widget-n-tabs\" data-id=\"a4214ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;tabs_justify_horizontal&quot;:&quot;stretch&quot;,&quot;horizontal_scroll_mobile&quot;:&quot;disable&quot;,&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"172102829\" aria-label=\"Registerkarten. \u00d6ffnen Sie Eintr\u00e4ge mit der Eingabetaste oder der Leertaste, schlie\u00dfen Sie sie mit der Escape-Taste und navigieren Sie mit den Pfeiltasten.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-1721028291\" data-tab-title-id=\"e-n-tab-title-1721028291\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-1721028291\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tAllgemeines\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1721028292\" data-tab-title-id=\"e-n-tab-title-1721028292\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1721028292\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tKosten\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1721028293\" data-tab-title-id=\"e-n-tab-title-1721028293\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1721028293\" style=\"--n-tabs-title-order: 3;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tFunktionsweise\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1721028294\" data-tab-title-id=\"e-n-tab-title-1721028294\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1721028294\" style=\"--n-tabs-title-order: 4;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tEinsatzbereich\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1721028295\" data-tab-title-id=\"e-n-tab-title-1721028295\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1721028295\" style=\"--n-tabs-title-order: 5;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tAblauf\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-1721028291\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1721028291\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-c7fc7c3 e-con-full e-flex e-con e-child\" data-id=\"c7fc7c3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c185d2c elementor-widget elementor-widget-n-accordion\" data-id=\"c185d2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2020\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2020\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Was ist eine Sockelheizung? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2020\" class=\"elementor-element elementor-element-76d7790 e-con-full e-flex e-con e-child\" data-id=\"76d7790\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-92927a6 elementor-widget elementor-widget-text-editor\" data-id=\"92927a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Sockelheizung ist ein elektrischer oder wasserf\u00fchrender Heizk\u00f6rper in der Form einer Sockelleiste, der sich entlang der gesamten Wandl\u00e4nge erstreckt. Dieser Heizk\u00f6rper erw\u00e4rmt gleichm\u00e4ssig die Oberfl\u00e4che der Wand, die dann, \u00e4hnlich wie ein Kachelofen, W\u00e4rme in den Raum abstrahlt und so den Raum heizt. Die Sockelheizung wird auch Sockelleistenheizung oder Fuss- bzw. Randleistenheizung genannt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2021\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2021\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Was kostet eine Sockelheizung? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2021\" class=\"elementor-element elementor-element-33ea3dd e-con-full e-flex e-con e-child\" data-id=\"33ea3dd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2bfb053 elementor-widget elementor-widget-text-editor\" data-id=\"2bfb053\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Sockelheizung kostet CHF 500 \u2013 1\u2019000 je Laufmeter exklusive Einbau. Im Vergleich zu einem herk\u00f6mmlichen Radiator l\u00e4sst sich damit bis zu 30% Energie sparen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2022\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2022\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Wie funktioniert eine Sockelheizung? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2022\" class=\"elementor-element elementor-element-2c73da6 e-con-full e-flex e-con e-child\" data-id=\"2c73da6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b157955 elementor-widget elementor-widget-text-editor\" data-id=\"b157955\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Sockelheizung macht sich den Coand\u0103-Effekt zunutze: Er bewirkt, dass sich str\u00f6mende Medien, wie warme Luft, an einer Oberfl\u00e4che anschmiegen, statt sich von ihr abzul\u00f6sen. Entsprechend bildet die Sockelheizung einen d\u00fcnnen Film warmer Luft auf der gesamten Wandoberfl\u00e4che. Dadurch erw\u00e4rmt sich die Wand gleichm\u00e4ssig und strahlt anschliessend, wie ein Kachelofen, W\u00e4rme in den Raum ab.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2023\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2023\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Wer ist Haustrocknung.ch? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2023\" class=\"elementor-element elementor-element-5b950ec e-con-full e-flex e-con e-child\" data-id=\"5b950ec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9efa3da elementor-widget elementor-widget-text-editor\" data-id=\"9efa3da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir sind seit 2010 auf die Entfeuchtung von Geb\u00e4uden spezialisiert, die wir mit innovativen Systemen trockenlegen. Die Haustrocknung.ch GmbH ist eine inhabergef\u00fchrte Firma mit Sitz im Kanton Bern. Werfen Sie einen Blick auf unsere <a title=\"Zu den Referenzen wechseln\" href=\"\/de\/referenzen\/\">Referenzen<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Was ist eine Sockelheizung?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Die Sockelheizung ist ein elektrischer oder wasserf\\u00fchrender Heizk\\u00f6rper in der Form einer Sockelleiste, der sich entlang der gesamten Wandl\\u00e4nge erstreckt. Dieser Heizk\\u00f6rper erw\\u00e4rmt gleichm\\u00e4ssig die Oberfl\\u00e4che der Wand, die dann, \\u00e4hnlich wie ein Kachelofen, W\\u00e4rme in den Raum abstrahlt und so den Raum heizt. Die Sockelheizung wird auch Sockelleistenheizung oder Fuss- bzw. Randleistenheizung genannt.\"}},{\"@type\":\"Question\",\"name\":\"Was kostet eine Sockelheizung?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Die Sockelheizung kostet CHF 500 \\u2013 1\\u2019000 je Laufmeter exklusive Einbau. Im Vergleich zu einem herk\\u00f6mmlichen Radiator l\\u00e4sst sich damit bis zu 30% Energie sparen.\"}},{\"@type\":\"Question\",\"name\":\"Wie funktioniert eine Sockelheizung?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Die Sockelheizung macht sich den Coand\\u0103-Effekt zunutze: Er bewirkt, dass sich str\\u00f6mende Medien, wie warme Luft, an einer Oberfl\\u00e4che anschmiegen, statt sich von ihr abzul\\u00f6sen. Entsprechend bildet die Sockelheizung einen d\\u00fcnnen Film warmer Luft auf der gesamten Wandoberfl\\u00e4che. Dadurch erw\\u00e4rmt sich die Wand gleichm\\u00e4ssig und strahlt anschliessend, wie ein Kachelofen, W\\u00e4rme in den Raum ab.\"}},{\"@type\":\"Question\",\"name\":\"Wer ist Haustrocknung.ch?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Wir sind seit 2010 auf die Entfeuchtung von Geb\\u00e4uden spezialisiert, die wir mit innovativen Systemen trockenlegen. Die Haustrocknung.ch GmbH ist eine inhabergef\\u00fchrte Firma mit Sitz im Kanton Bern. Werfen Sie einen Blick auf unsere Referenzen.\"}}]}<\/script>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cdddfee elementor-widget elementor-widget-button\" data-id=\"cdddfee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#offerte\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt unverbindlich anfragen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1721028292\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1721028292\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\" elementor-element elementor-element-7841aa2 e-con-full e-flex e-con e-child\" data-id=\"7841aa2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c76a0dd elementor-widget elementor-widget-n-accordion\" data-id=\"c76a0dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2090\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2090\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Wie viel kostet eine Sockelheizung? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2090\" class=\"elementor-element elementor-element-51340bd e-con-full e-flex e-con e-child\" data-id=\"51340bd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4203618 elementor-widget elementor-widget-text-editor\" data-id=\"4203618\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Eine Sockelheizung f\u00fcr einen Raum von 25 Quadratmeter kostet ungef\u00e4hr CHF 500 \u2013 1\u2019000 je Laufmeter exkl. Einbau.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2091\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2091\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Wie viel kann ich mit einer Sockelheizung einsparen? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2091\" class=\"elementor-element elementor-element-1f709ed e-con-full e-flex e-con e-child\" data-id=\"1f709ed\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ccf0c3a elementor-widget elementor-widget-text-editor\" data-id=\"ccf0c3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Im Vergleich zu herk\u00f6mmlichen Heizradiatoren ist die Sockelheizung bis zu 30% sparsamer im Verbrauch.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2092\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2092\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Wie hoch sind die Kosten f\u00fcr den Verbrauch der Sockelheizung? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2092\" class=\"elementor-element elementor-element-99dd162 e-con-full e-flex e-con e-child\" data-id=\"99dd162\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5aaad91 elementor-widget elementor-widget-text-editor\" data-id=\"5aaad91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Eine wasserf\u00fchrende Sockelheizung verbraucht 20% bis 30% weniger Energie als herk\u00f6mmliche Heizradiatoren. Elektrische Sockelheizleisten verursachen demgegen\u00fcber Stromkosten von etwa CHF 0.1 pro Meter und Betriebsstunde. Elektronische Sockelheizleisten d\u00fcrfen in der Schweiz nicht als Prim\u00e4rheizung eingesetzt werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2093\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2093\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Warum ist die Sockelheizung sparsamer als herk\u00f6mmliche Heizradiatoren? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2093\" class=\"elementor-element elementor-element-bc10d17 e-con-full e-flex e-con e-child\" data-id=\"bc10d17\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b08a37a elementor-widget elementor-widget-text-editor\" data-id=\"b08a37a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bei herk\u00f6mmlichen Heizradiatoren sammelt sich ein Grossteil der W\u00e4rme ungenutzt unter der Decke. Die Sockelheizung verteilt die W\u00e4rme gleichm\u00e4ssiger im Raum als herk\u00f6mmliche Heizradiatoren, wodurch bis zu 30% Energie gespart wird.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a8ee59 elementor-widget elementor-widget-button\" data-id=\"4a8ee59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#offerte\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt unverbindlich anfragen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1721028293\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1721028293\" data-tab-index=\"3\" style=\"--n-tabs-title-order: 3;\" class=\" elementor-element elementor-element-9719d96 e-con-full e-flex e-con e-child\" data-id=\"9719d96\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e87c3c elementor-widget elementor-widget-n-accordion\" data-id=\"6e87c3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1150\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1150\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Wie funktioniert die Fussleistenheizung? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1150\" class=\"elementor-element elementor-element-6b1092e e-con-full e-flex e-con e-child\" data-id=\"6b1092e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aa24bb5 elementor-widget elementor-widget-text-editor\" data-id=\"aa24bb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Sockelheizung nutzt den Coand\u0103-Effekt: Dieser bewirkt, dass sich str\u00f6mende Medien, wie warme Luft, einer Oberfl\u00e4che entlangbewegen, anstatt sich von ihr zu l\u00f6sen. Infolgedessen entsteht an der gesamten Wandoberfl\u00e4che ein d\u00fcnner Film aus warmer Luft. Dies erm\u00f6glicht eine gleichm\u00e4ssige Erw\u00e4rmung der Wand, die dann wie ein Kachelofen W\u00e4rme in den Raum abstrahlt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1151\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1151\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Welches sind die Vorteile einer Sockelleistenheizung? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1151\" class=\"elementor-element elementor-element-a0527bb e-con-full e-flex e-con e-child\" data-id=\"a0527bb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c7c8045 elementor-widget elementor-widget-text-editor\" data-id=\"c7c8045\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Sockelheizung ist bis zu 30% sparsamer als herk\u00f6mmliche Radiatoren, da sie lediglich die Wandoberfl\u00e4che erw\u00e4rmt und nicht das gesamte Raumluft-Volumen. Sie gew\u00e4hrleistet eine gleichm\u00e4ssige W\u00e4rmeverteilung ohne kalte Ecken am Boden-Wand-\u00dcbergang und minimiert das Schimmelrisiko durch trockene Wandoberfl\u00e4chen. Die angenehme Strahlungsw\u00e4rme erzeugt zudem eine gem\u00fctliche Atmosph\u00e4re, \u00e4hnlich wie ein Kachelofen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1152\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1152\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Wie unterscheiden sich Sockelheizleisten von Heizradiatoren? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1152\" class=\"elementor-element elementor-element-4f5a65d e-con-full e-flex e-con e-child\" data-id=\"4f5a65d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3fbf619 elementor-widget elementor-widget-text-editor\" data-id=\"3fbf619\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Herk\u00f6mmliche Heizradiatoren erw\u00e4rmen den Raum \u00fcber die Luft, die sich nur sehr ungleichm\u00e4ssig im Raum verteilt (sogenannte Konvektionsw\u00e4rme). Im Gegensatz dazu erw\u00e4rmen Sockelheizungen die Wandoberfl\u00e4chen, welche die W\u00e4rme gleichm\u00e4ssig an die sich im Raum befindlichen Personen und Gegenst\u00e4nde abstrahlen (sogenannte Strahlungsw\u00e4rme).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1153\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1153\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Wie unterscheidet sich Strahlungsw\u00e4rme im Vergleich zur Konvektionsw\u00e4rme? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1153\" class=\"elementor-element elementor-element-8766f09 e-con-full e-flex e-con e-child\" data-id=\"8766f09\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0754247 elementor-widget elementor-widget-text-editor\" data-id=\"0754247\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Strahlungsw\u00e4rme wird bei identischer Raumluft-Temperatur intensiver wahrgenommen als Konvektionsw\u00e4rme. Dies l\u00e4sst sich am Beispiel des Sonnenbadens veranschaulichen: Schiebt sich eine Wolke direkt vor die Sonne und schirmt so einen Teil der Strahlungsw\u00e4rme ab, f\u00e4ngt man an zu fr\u00f6steln, obwohl sich die Lufttemperatur nicht schlagartig ver\u00e4ndert hat.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64f5ec5 elementor-widget elementor-widget-button\" data-id=\"64f5ec5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#offerte\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt unverbindlich anfragen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1721028294\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1721028294\" data-tab-index=\"4\" style=\"--n-tabs-title-order: 4;\" class=\" elementor-element elementor-element-4561cbd e-con-full e-flex e-con e-child\" data-id=\"4561cbd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69dcf50 elementor-widget elementor-widget-n-accordion\" data-id=\"69dcf50\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1110\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1110\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Vermag eine Sockelleistenheizung ein Haus selbst\u00e4ndig zu heizen? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1110\" class=\"elementor-element elementor-element-a6e5250 e-con-full e-flex e-con e-child\" data-id=\"a6e5250\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-465ba20 elementor-widget elementor-widget-text-editor\" data-id=\"465ba20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ja, wasserf\u00fchrende Sockelheizleisten k\u00f6nnen sowohl als alleinige Hauptheizung wie auch erg\u00e4nzend zu bestehenden Heizsystemen eingesetzt werden. In der Schweiz darf die elektrische Sockelheizung nicht als Prim\u00e4rheizung eingesetzt werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1111\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1111\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> M\u00fcssen die W\u00e4nde frei von M\u00f6beln und Bildern sein? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1111\" class=\"elementor-element elementor-element-22a7baf e-con-full e-flex e-con e-child\" data-id=\"22a7baf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a501e86 elementor-widget elementor-widget-text-editor\" data-id=\"a501e86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nein, wichtig ist dass zwischen M\u00f6bel und W\u00e4nden ein Abstand von wenigen Zentimetern besteht, damit die warme Luft an der Wand entlang aufsteigen, vorbei kann. Je nach Gr\u00f6sse und Beschaffenheit der Bilder, sollten diese auch 1-2 cm Abstand von der Wand haben. Gerade dickere Bilder sollten also idealerweise nicht vollfl\u00e4chig an der Wand anliegen, so dass die warme Luft hinter den Bildern durchziehen kann.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1112\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1112\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Kann die Sockelleistenheizung auch entlang von Glasfronten montiert werden? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1112\" class=\"elementor-element elementor-element-d465c5e e-con-full e-flex e-con e-child\" data-id=\"d465c5e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34f8c20 elementor-widget elementor-widget-text-editor\" data-id=\"34f8c20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ja, wenn es um eine gut isolierende Mehrfachverglasung handelt, wie sie bei Neubauten zum Einsatz kommt, kann die Sockelleistenheizung auch bei Glasfronten eingesetzt werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1113\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1113\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Wie wirkt sich die Raumh\u00f6he auf die Heizleistung aus? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1113\" class=\"elementor-element elementor-element-ec01a6f e-con-full e-flex e-con e-child\" data-id=\"ec01a6f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-037797d elementor-widget elementor-widget-text-editor\" data-id=\"037797d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Raumh\u00f6he spielt in Bezug auf die Leistungsf\u00e4higkeit der Fussleistenheizung nur eine untergeordnete Rolle, zumal die Wandoberfl\u00e4che gleichm\u00e4ssig erw\u00e4rmt wird. Der Temperaturunterschied zwischen Boden und Decke betr\u00e4gt bei der Fussleistenheizung h\u00f6chstens 1 \u00b0C. Bei schlecht isolierten R\u00e4umen mit einer Konvektionsheizung betr\u00e4gt der W\u00e4rmeunterschied zwischen Boden und Decke bis zu 6\u00b0C.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e0e232 elementor-widget elementor-widget-button\" data-id=\"8e0e232\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#offerte\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt unverbindlich anfragen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1721028295\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1721028295\" data-tab-index=\"5\" style=\"--n-tabs-title-order: 5;\" class=\" elementor-element elementor-element-9d1efc2 e-con-full e-flex e-con e-child\" data-id=\"9d1efc2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d01b027 elementor-widget elementor-widget-n-accordion\" data-id=\"d01b027\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2180\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2180\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Wie l\u00e4uft die Auftragsabwicklung ab? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2180\" class=\"elementor-element elementor-element-d128b8c e-con-full e-flex e-con e-child\" data-id=\"d128b8c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a54a78b elementor-widget elementor-widget-text-editor\" data-id=\"a54a78b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unsere erfahrenen Experten rufen Sie, nach Ihrem Kontakt per Anmeldeformular, f\u00fcr eine Erstberatung an. Wenn Sie Interesse haben, dann kommen wir f\u00fcr eine Vorort-Analyse zum betroffenen Objekt. Vorort analysieren wir, wie wir Ihnen am Besten helfen k\u00f6nnen, bzw. ob sich eine Sockelheizung f\u00fcr Ihr Objekt eignet bzw. wie sie dimensioniert sein m\u00fcsste. Auf Basis der Besichtigung vor Ort machen wir Ihnen eine Offerte. Auf Basis der Offerte entscheiden Sie, ob Sie den Einbau w\u00fcnschen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2181\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2181\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Wie lange dauert die Montage einer Sockelheizung? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2181\" class=\"elementor-element elementor-element-4b5afa8 e-con-full e-flex e-con e-child\" data-id=\"4b5afa8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48b96cb elementor-widget elementor-widget-text-editor\" data-id=\"48b96cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dies h\u00e4ngt nat\u00fcrlich stark von der Gr\u00f6sse des Raumes ab sowie von der Menge der Heizleisten, die montiert werden m\u00fcssen. Es spielt auch eine Rolle, ob es sich dabei um elektrische oder wasserf\u00fchrende Heizleisten handelt. Als Faustregel rechnen wir ungef\u00e4hr mit einem halben Tag pro Raum mit einer Fl\u00e4che von 25 Quadratmetern.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2182\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2182\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Wie wird die Sockelleistenheizung richtig dimensioniert? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2182\" class=\"elementor-element elementor-element-6430305 e-con-full e-flex e-con e-child\" data-id=\"6430305\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d2afde elementor-widget elementor-widget-text-editor\" data-id=\"2d2afde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bei der Dimensionierung der Sockelleistenheizung gleichen wir den W\u00e4rmebedarf bzgl. der Raumgr\u00f6sse mit der zur Verf\u00fcgung stehenden Leistung ab, die prim\u00e4r von der Gr\u00f6sse der Wandoberfl\u00e4che bestimmt wird. Oft gen\u00fcgt bereits eine Sockelheizung entlang der Aussenwand, um den Raum ausreichend zu heizen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2183\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2183\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Welche Faktoren sind ausschlaggebend f\u00fcr die Leistungsf\u00e4higkeit der Sockelheizung? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2183\" class=\"elementor-element elementor-element-fd8f9f5 e-con-full e-flex e-con e-child\" data-id=\"fd8f9f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e55dad elementor-widget elementor-widget-text-editor\" data-id=\"5e55dad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Leistungsf\u00e4higkeit der Sockelheizung ist abh\u00e4ngig von der Gr\u00f6sse der Wandfl\u00e4che, die zur Verf\u00fcgung steht. Je gr\u00f6sser die erw\u00e4rmte Wandoberfl\u00e4che, desto mehr Strahlungsw\u00e4rme kann sie in den Raum abstrahlen und desto gr\u00f6sser ist die Heizleistung des Systems.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dece80f elementor-widget elementor-widget-button\" data-id=\"dece80f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#offerte\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt unverbindlich anfragen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03e69cf elementor-widget elementor-widget-heading\" data-id=\"03e69cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fragen &amp; Antworten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-153617a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"153617a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-709c5de\" data-id=\"709c5de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4cd1001 elementor-widget elementor-widget-heading\" data-id=\"4cd1001\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Montage<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7a309b elementor-widget elementor-widget-heading\" data-id=\"e7a309b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Einfach und schnell installierte Heizleisten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e43fb49 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e43fb49\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-876a9f0\" data-id=\"876a9f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abd4059 elementor-widget elementor-widget-image\" data-id=\"abd4059\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/08\/sockelleistenheizung-1024x683.jpg\" class=\"attachment-large size-large wp-image-4790\" alt=\"Sockelleistenheizung\" srcset=\"https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/08\/sockelleistenheizung-1024x683.jpg 1024w, https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/08\/sockelleistenheizung-300x200.jpg 300w, https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/08\/sockelleistenheizung-768x512.jpg 768w, https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/08\/sockelleistenheizung-18x12.jpg 18w, https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/08\/sockelleistenheizung.jpg 1062w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-880f4c4 elementor-widget elementor-widget-text-editor\" data-id=\"880f4c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a9 https:\/\/energy-com.de\/sockelheizleisten\/das-prinzip\/<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-85cd8b5\" data-id=\"85cd8b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be220b2 elementor-widget elementor-widget-text-editor\" data-id=\"be220b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>Sockelheizleisten sehen aus wie Fussleisten.<br \/><br \/><\/li><li>Sockelleistenheizungen, funktionieren mit dem Prinzip der Strahlungsw\u00e4rme.<br \/><br \/><\/li><li>Sockelheizungen werden in Verbindung zwischen Boden und Wand im ganzen Raum montiert.<br \/><br \/><\/li><li>Sockelleistenheizungen funktionieren je nach gew\u00e4hlter Ausf\u00fchrung entweder elektrisch oder wassergef\u00fchrt.<br \/><br \/><\/li><li>Die Sockelheizleiste steuert man mit einem Thermostat.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c296d2d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c296d2d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8c4eb75\" data-id=\"8c4eb75\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a33c39d elementor-widget elementor-widget-heading\" data-id=\"a33c39d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Mehr Komfort zu geringeren Kosten<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eeecc38 elementor-widget elementor-widget-heading\" data-id=\"eeecc38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Die Vorteile der Sockelheizung auf einen Blick<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-91d307b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"91d307b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0703baf\" data-id=\"0703baf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-305a534 elementor-widget elementor-widget-text-editor\" data-id=\"305a534\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>Energieeffizient &amp; umweltfreundlich<br \/><br \/><\/li><li>Energiesparend &amp; heizkostensenkend<br \/><br \/><\/li><li>Gesund &amp; angenehm dank Strahlungsw\u00e4rme<br \/><br \/><\/li><li>Flexibel einsetzbar, flexibel zu betreiben<br \/><br \/><\/li><li>Schnell &amp; einfach auch nachtr\u00e4glich zu montieren<br \/><br \/><\/li><li>Platzsparend &amp; \u00e4sthetisch<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b30e5b0\" data-id=\"b30e5b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8523be0 elementor-widget elementor-widget-image\" data-id=\"8523be0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"123\" src=\"https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/08\/tuev-rheinland.png\" class=\"attachment-large size-large wp-image-4789\" alt=\"T\u00dcV gepr\u00fcfte Sockelheizleisten\" srcset=\"https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/08\/tuev-rheinland.png 225w, https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/08\/tuev-rheinland-18x10.png 18w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fdb0fc9 elementor-widget elementor-widget-text-editor\" data-id=\"fdb0fc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die elektrisch beheizte Sockelheizleiste \u00abECHL-3_E-2000\u00bb ist von der <strong>T\u00dcV Rheinland LGA Products GmbH<\/strong> gepr\u00fcft worden und erf\u00fcllt die definierten Anforderungen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9852d56 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9852d56\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-142805e\" data-id=\"142805e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-125def8 elementor-widget elementor-widget-heading\" data-id=\"125def8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Erg\u00e4nzende Massnahmen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-339bef9 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"339bef9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-fc1b484\" data-id=\"fc1b484\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-99dd3ca elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"99dd3ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cbbd45 elementor-widget elementor-widget-text-editor\" data-id=\"4cbbd45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a title=\"Zur Solarheizung wechseln\" href=\"\/de\/solarheizung\/\">Solarheizung \u203a<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07ba41a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"07ba41a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65f3b45 elementor-widget elementor-widget-text-editor\" data-id=\"65f3b45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a title=\"Zur Kellerl\u00fcftung wechseln\" href=\"\/de\/kellerlueftung\/\">Kellerl\u00fcftung \u203a<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-151544e elementor-hidden-mobile elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"151544e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f341150\" data-id=\"f341150\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dbefe27 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"dbefe27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94b0c57 elementor-widget elementor-widget-text-editor\" data-id=\"94b0c57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a title=\"Zur Kellerentfeuchtung wechseln\" href=\"\/de\/kellerentfeuchtung\/\">Kellerentfeuchtung \u203a<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-103f1cb elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"103f1cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0366630 elementor-widget elementor-widget-text-editor\" data-id=\"0366630\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a title=\"Zum Feuchtigkeitsgutachten wechseln\" href=\"\/de\/feuchtigkeitsmessung\/\">Feuchtigkeitsgutachten \u203a<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddd2199 elementor-hidden-mobile elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ddd2199\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ca973e2\" data-id=\"ca973e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60d706e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"60d706e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4adc191 elementor-widget elementor-widget-text-editor\" data-id=\"4adc191\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a title=\"Zur Einzelrauml\u00fcftung wechseln\" href=\"\/de\/einzelraumlueftung\/\">Einzelrauml\u00fcftung \u203a<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d68794 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9d68794\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59f833e elementor-widget elementor-widget-text-editor\" data-id=\"59f833e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a title=\"Zur Radon-L\u00fcftung wechseln\" href=\"\/de\/radon-lueftung\/\">Radon-L\u00fcftung \u203a<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92228e8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"92228e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Kosten sparen mit einer Sockelheizung Bei den \u00fcblichen Radiatoren bezahlen Sie mind. 20\u00a0% zu viel f\u00fcrs Heizen, weil sich ein Gross\u00adteil der W\u00e4rme ungenutzt unter der Decke ansammelt. Heizen Sie Ihre R\u00e4ume gleich\u00adm\u00e4ssig mit einer Sockel\u00adheizung und bezahlen Sie nicht mehr zu viel. Jetzt Offerte anfragen So funktioniert&#8217;s Sockelleistenheizung Die Sockelleistenhei\u00adzung ist ein lang\u00adge\u00adzogener Heiz\u00adk\u00f6rper [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4790,"parent":0,"menu_order":501,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-193","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sockelheizung: Mit der Fussleistenheizung zu tieferen Kosten<\/title>\n<meta name=\"description\" content=\"Sockelheizungen sparen bis zu 30% der Heizkosten dank gleichm\u00e4ssiger W\u00e4rmeverteilung \u2713 Jetzt mehr erfahren!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.haustrocknung.ch\/de\/sockelheizung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sockelheizung: Mit der Fussleistenheizung zu tieferen Kosten\" \/>\n<meta property=\"og:description\" content=\"Sockelheizungen sparen bis zu 30% der Heizkosten dank gleichm\u00e4ssiger W\u00e4rmeverteilung \u2713 Jetzt mehr erfahren!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.haustrocknung.ch\/de\/sockelheizung\/\" \/>\n<meta property=\"og:site_name\" content=\"Haustrocknung.ch\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-20T22:28:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/08\/sockelleistenheizung.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1062\" \/>\n\t<meta property=\"og:image:height\" content=\"708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"16\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.haustrocknung.ch\\\/sockelheizung\\\/\",\"url\":\"https:\\\/\\\/www.haustrocknung.ch\\\/sockelheizung\\\/\",\"name\":\"Sockelheizung: Mit der Fussleistenheizung zu tieferen Kosten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.haustrocknung.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.haustrocknung.ch\\\/sockelheizung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.haustrocknung.ch\\\/sockelheizung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.haustrocknung.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/sockelleistenheizung.jpg\",\"datePublished\":\"2023-06-29T04:41:11+00:00\",\"dateModified\":\"2026-06-20T22:28:03+00:00\",\"description\":\"Sockelheizungen sparen bis zu 30% der Heizkosten dank gleichm\u00e4ssiger W\u00e4rmeverteilung \u2713 Jetzt mehr erfahren!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.haustrocknung.ch\\\/sockelheizung\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.haustrocknung.ch\\\/sockelheizung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/www.haustrocknung.ch\\\/sockelheizung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.haustrocknung.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/sockelleistenheizung.jpg\",\"contentUrl\":\"https:\\\/\\\/www.haustrocknung.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/sockelleistenheizung.jpg\",\"width\":1062,\"height\":708,\"caption\":\"Sockelleistenheizung\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.haustrocknung.ch\\\/sockelheizung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.haustrocknung.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sockelheizung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.haustrocknung.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.haustrocknung.ch\\\/\",\"name\":\"Haustrocknung.ch\",\"description\":\"Elektrophysikalische Mauerentfeuchtung\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.haustrocknung.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.haustrocknung.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.haustrocknung.ch\\\/#organization\",\"name\":\"Haustrocknung.ch\",\"url\":\"https:\\\/\\\/www.haustrocknung.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/www.haustrocknung.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.haustrocknung.ch\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/haustrocknung-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.haustrocknung.ch\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/haustrocknung-logo.svg\",\"width\":374,\"height\":86,\"caption\":\"Haustrocknung.ch\"},\"image\":{\"@id\":\"https:\\\/\\\/www.haustrocknung.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sockelheizung: Mit der Fussleistenheizung zu tieferen Kosten","description":"Sockelheizungen sparen bis zu 30% der Heizkosten dank gleichm\u00e4ssiger W\u00e4rmeverteilung \u2713 Jetzt mehr erfahren!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.haustrocknung.ch\/de\/sockelheizung\/","og_locale":"de_DE","og_type":"article","og_title":"Sockelheizung: Mit der Fussleistenheizung zu tieferen Kosten","og_description":"Sockelheizungen sparen bis zu 30% der Heizkosten dank gleichm\u00e4ssiger W\u00e4rmeverteilung \u2713 Jetzt mehr erfahren!","og_url":"https:\/\/www.haustrocknung.ch\/de\/sockelheizung\/","og_site_name":"Haustrocknung.ch","article_modified_time":"2026-06-20T22:28:03+00:00","og_image":[{"width":1062,"height":708,"url":"https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/08\/sockelleistenheizung.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"16\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.haustrocknung.ch\/sockelheizung\/","url":"https:\/\/www.haustrocknung.ch\/sockelheizung\/","name":"Sockelheizung: Mit der Fussleistenheizung zu tieferen Kosten","isPartOf":{"@id":"https:\/\/www.haustrocknung.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.haustrocknung.ch\/sockelheizung\/#primaryimage"},"image":{"@id":"https:\/\/www.haustrocknung.ch\/sockelheizung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/08\/sockelleistenheizung.jpg","datePublished":"2023-06-29T04:41:11+00:00","dateModified":"2026-06-20T22:28:03+00:00","description":"Sockelheizungen sparen bis zu 30% der Heizkosten dank gleichm\u00e4ssiger W\u00e4rmeverteilung \u2713 Jetzt mehr erfahren!","breadcrumb":{"@id":"https:\/\/www.haustrocknung.ch\/sockelheizung\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.haustrocknung.ch\/sockelheizung\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/www.haustrocknung.ch\/sockelheizung\/#primaryimage","url":"https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/08\/sockelleistenheizung.jpg","contentUrl":"https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/08\/sockelleistenheizung.jpg","width":1062,"height":708,"caption":"Sockelleistenheizung"},{"@type":"BreadcrumbList","@id":"https:\/\/www.haustrocknung.ch\/sockelheizung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.haustrocknung.ch\/"},{"@type":"ListItem","position":2,"name":"Sockelheizung"}]},{"@type":"WebSite","@id":"https:\/\/www.haustrocknung.ch\/#website","url":"https:\/\/www.haustrocknung.ch\/","name":"Haustrocknung.ch","description":"Elektrophysikalische Mauerentfeuchtung","publisher":{"@id":"https:\/\/www.haustrocknung.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.haustrocknung.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Organization","@id":"https:\/\/www.haustrocknung.ch\/#organization","name":"Haustrocknung.ch","url":"https:\/\/www.haustrocknung.ch\/","logo":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/www.haustrocknung.ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/06\/haustrocknung-logo.svg","contentUrl":"https:\/\/www.haustrocknung.ch\/wp-content\/uploads\/2023\/06\/haustrocknung-logo.svg","width":374,"height":86,"caption":"Haustrocknung.ch"},"image":{"@id":"https:\/\/www.haustrocknung.ch\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.haustrocknung.ch\/de\/wp-json\/wp\/v2\/pages\/193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.haustrocknung.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.haustrocknung.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.haustrocknung.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.haustrocknung.ch\/de\/wp-json\/wp\/v2\/comments?post=193"}],"version-history":[{"count":0,"href":"https:\/\/www.haustrocknung.ch\/de\/wp-json\/wp\/v2\/pages\/193\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.haustrocknung.ch\/de\/wp-json\/wp\/v2\/media\/4790"}],"wp:attachment":[{"href":"https:\/\/www.haustrocknung.ch\/de\/wp-json\/wp\/v2\/media?parent=193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}